{"id":353,"date":"2011-04-06T10:50:00","date_gmt":"2011-04-06T08:50:00","guid":{"rendered":"http:\/\/jososabadell.cat\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/"},"modified":"2018-04-13T15:02:27","modified_gmt":"2018-04-13T13:02:27","slug":"nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi","status":"publish","type":"post","link":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/","title":{"rendered":"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI."},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s1600\/punt%2Bde%2Bllibre%2B2011.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" style=\"display:block; margin:0px auto 10px; text-align:center;cursor:pointer; cursor:hand;width: 139px; height: 400px;\" src=\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg\" border=\"0\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5592392989612388946\" \/><\/a><\/p>\n<p><span lang=\"CA\">Ja tenim en marxa una nova edici\u00f3 del <b>concurs de punts de llibre<\/b> per la diada de Sant Jordi que des de fa uns anys l\u2019 Escola Joso de Sabadell organitza principalment per als seus alumnes, per\u00f2 que tamb\u00e9 queda obert per amics i ex alumnes. La mida, \u00e9s la resultant de doblegar un din a 4 dues vegades i la t\u00e8cnica i contingut \u00e9s lliure. Tamb\u00e9 podeu presentar tots els punts de llibre que volgueu. El termini m\u00e0xim d\u2019 entrega a l centre de Sabadell \u00e9s del dimarts 26 d\u2019 Abril de 2011.<\/span><\/p>\n<p><span lang=\"CA\">A mida que passen els anys, el nivell va creixent de forma exponencial. Per tant, si us voleu fer una idea de per on van els trets podeu consultar al mateix blog els guanyadors d\u2019 edicions anteriors per tal de, si \u00e9s possible, superar aquests treballs.<\/span><\/p>\n<p><span lang=\"CA\">Esperem una bona participaci\u00f3 en nombre i quantitat de treballs.<\/span><\/p>\n<p><span lang=\"CA\">Fins aviat ! <\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Ja tenim en marxa una nova edici\u00f3 del concurs de punts de llibre per la diada de Sant Jordi que des de fa uns anys l\u2019 Escola Joso de Sabadell organitza principalment per als seus alumnes, per\u00f2 que tamb\u00e9 queda obert per amics i ex alumnes. La mida, \u00e9s la resultant de doblegar un din [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-353","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell\" \/>\n<meta property=\"og:description\" content=\"Ja tenim en marxa una nova edici\u00f3 del concurs de punts de llibre per la diada de Sant Jordi que des de fa uns anys l\u2019 Escola Joso de Sabadell organitza principalment per als seus alumnes, per\u00f2 que tamb\u00e9 queda obert per amics i ex alumnes. La mida, \u00e9s la resultant de doblegar un din [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/\" \/>\n<meta property=\"og:site_name\" content=\"Escola Joso Sabadell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escolajososabadell\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-06T08:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-13T13:02:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg\" \/>\n<meta name=\"author\" content=\"Joso Sabadell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EscolaJosoSbd\" \/>\n<meta name=\"twitter:site\" content=\"@EscolaJosoSbd\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joso Sabadell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/\",\"url\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/\",\"name\":\"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell\",\"isPartOf\":{\"@id\":\"https:\/\/jososabadell.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg\",\"datePublished\":\"2011-04-06T08:50:00+00:00\",\"dateModified\":\"2018-04-13T13:02:27+00:00\",\"author\":{\"@id\":\"https:\/\/jososabadell.cat\/#\/schema\/person\/233e57003be70aa898d35bfb3ee0fb72\"},\"breadcrumb\":{\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage\",\"url\":\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg\",\"contentUrl\":\"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/jososabadell.cat\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jososabadell.cat\/#website\",\"url\":\"https:\/\/jososabadell.cat\/\",\"name\":\"Escola Joso Sabadell\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jososabadell.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/jososabadell.cat\/#\/schema\/person\/233e57003be70aa898d35bfb3ee0fb72\",\"name\":\"Joso Sabadell\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/jososabadell.cat\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/5aa9d058168d026c6f8d651849c8cf5d?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/5aa9d058168d026c6f8d651849c8cf5d?s=96&d=mm&r=g\",\"caption\":\"Joso Sabadell\"},\"sameAs\":[\"http:\/\/jososabadell.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/","og_locale":"es_ES","og_type":"article","og_title":"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell","og_description":"Ja tenim en marxa una nova edici\u00f3 del concurs de punts de llibre per la diada de Sant Jordi que des de fa uns anys l\u2019 Escola Joso de Sabadell organitza principalment per als seus alumnes, per\u00f2 que tamb\u00e9 queda obert per amics i ex alumnes. La mida, \u00e9s la resultant de doblegar un din [&hellip;]","og_url":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/","og_site_name":"Escola Joso Sabadell","article_publisher":"https:\/\/www.facebook.com\/escolajososabadell\/","article_published_time":"2011-04-06T08:50:00+00:00","article_modified_time":"2018-04-13T13:02:27+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg","type":"","width":"","height":""}],"author":"Joso Sabadell","twitter_card":"summary_large_image","twitter_creator":"@EscolaJosoSbd","twitter_site":"@EscolaJosoSbd","twitter_misc":{"Escrito por":"Joso Sabadell","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/","url":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/","name":"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI. - Escola Joso Sabadell","isPartOf":{"@id":"https:\/\/jososabadell.cat\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage"},"image":{"@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg","datePublished":"2011-04-06T08:50:00+00:00","dateModified":"2018-04-13T13:02:27+00:00","author":{"@id":"https:\/\/jososabadell.cat\/#\/schema\/person\/233e57003be70aa898d35bfb3ee0fb72"},"breadcrumb":{"@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#primaryimage","url":"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg","contentUrl":"http:\/\/1.bp.blogspot.com\/-A6pQXkxTckY\/TZwry1Y7MlI\/AAAAAAAAAU4\/HRi_vdMdSlI\/s400\/punt%2Bde%2Bllibre%2B2011.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/jososabadell.cat\/es\/2011\/04\/06\/nova-edicio-del-concurs-de-punt-de-llibre-per-la-diada-de-sant-jordi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/jososabadell.cat\/"},{"@type":"ListItem","position":2,"name":"NOVA EDICI\u00d3 DEL CONCURS DE PUNT DE LLIBRE PER LA DIADA DE SANT JORDI."}]},{"@type":"WebSite","@id":"https:\/\/jososabadell.cat\/#website","url":"https:\/\/jososabadell.cat\/","name":"&nbsp;Escola Joso Sabadell","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jososabadell.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/jososabadell.cat\/#\/schema\/person\/233e57003be70aa898d35bfb3ee0fb72","name":"Joso Sabadell","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jososabadell.cat\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/5aa9d058168d026c6f8d651849c8cf5d?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/5aa9d058168d026c6f8d651849c8cf5d?s=96&d=mm&r=g","caption":"Joso Sabadell"},"sameAs":["http:\/\/jososabadell.cat"]}]}},"_links":{"self":[{"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/posts\/353"}],"collection":[{"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/comments?post=353"}],"version-history":[{"count":1,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/posts\/353\/revisions"}],"predecessor-version":[{"id":789,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/posts\/353\/revisions\/789"}],"wp:attachment":[{"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/media?parent=353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/categories?post=353"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jososabadell.cat\/es\/wp-json\/wp\/v2\/tags?post=353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}